{"id":435,"count":1,"description":"","link":"https:\/\/marvista.com\/Yukiko\/en\/archives\/tag\/driving-theater-in-los-angeles","name":"Driving Theater in Los Angeles","slug":"driving-theater-in-los-angeles","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/marvista.com\/Yukiko\/wp-json\/wp\/v2\/tags\/435"}],"collection":[{"href":"https:\/\/marvista.com\/Yukiko\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/marvista.com\/Yukiko\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/marvista.com\/Yukiko\/wp-json\/wp\/v2\/posts?tags=435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}